{"id":9690,"date":"2025-06-10T10:36:43","date_gmt":"2025-06-10T08:36:43","guid":{"rendered":"https:\/\/a-eb.org\/?p=9690"},"modified":"2025-06-13T09:11:11","modified_gmt":"2025-06-13T07:11:11","slug":"vento-tra-i-capelli-gioia-nel-cuore","status":"publish","type":"post","link":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/","title":{"rendered":"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia"},"content":{"rendered":"<p>Nel video ufficiale dell\u2019associazione Harley Heads MC S\u00fcdtirol risuona il loro inno \u2013 e nel mezzo: scene toccanti del giro in moto insieme a giovani e giovani adulti con sindrome di Down provenienti da famiglie AEB della Val Pusteria. Da questo incontro speciale \u00e8 nata un\u2019amicizia autentica, che nessuno vorrebbe pi\u00f9 perdere. Porta gioia di vivere, un senso di unione \u2013 e dimostra quanto valore ci sia nel vero incontro.<\/p>\n<p>Video: <a href=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/09.06.2025-Harley-Heads-und-AEB.mp4\">Harley Heads con l&#8217;AEB<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel video ufficiale dell\u2019associazione Harley Heads MC S\u00fcdtirol risuona il loro inno \u2013 e nel mezzo: scene toccanti del giro&#8230;<\/p>\n","protected":false},"author":5,"featured_media":9682,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9690","post","type-post","status-publish","format-standard","has-post-thumbnail","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"og:description\" content=\"Nel video ufficiale dell\u2019associazione Harley Heads MC S\u00fcdtirol risuona il loro inno \u2013 e nel mezzo: scene toccanti del giro...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/\" \/>\n<meta property=\"og:site_name\" content=\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-10T08:36:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T07:11:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/Harley.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1255\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"a-eb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"a-eb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/\"},\"author\":{\"name\":\"a-eb\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/325fa69af067b3a181046f67c79c67ff\"},\"headline\":\"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia\",\"datePublished\":\"2025-06-10T08:36:43+00:00\",\"dateModified\":\"2025-06-13T07:11:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/\"},\"wordCount\":89,\"image\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Harley.png\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/\",\"name\":\"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Harley.png\",\"datePublished\":\"2025-06-10T08:36:43+00:00\",\"dateModified\":\"2025-06-13T07:11:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/325fa69af067b3a181046f67c79c67ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Harley.png\",\"contentUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Harley.png\",\"width\":1255,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/vento-tra-i-capelli-gioia-nel-cuore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\",\"url\":\"https:\\\/\\\/a-eb.org\\\/\",\"name\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"description\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-eb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/325fa69af067b3a181046f67c79c67ff\",\"name\":\"a-eb\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/author\\\/a-eb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/","og_locale":"it_IT","og_type":"article","og_title":"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","og_description":"Nel video ufficiale dell\u2019associazione Harley Heads MC S\u00fcdtirol risuona il loro inno \u2013 e nel mezzo: scene toccanti del giro...","og_url":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/","og_site_name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","article_published_time":"2025-06-10T08:36:43+00:00","article_modified_time":"2025-06-13T07:11:11+00:00","og_image":[{"width":1255,"height":713,"url":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/Harley.png","type":"image\/png"}],"author":"a-eb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"a-eb"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#article","isPartOf":{"@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/"},"author":{"name":"a-eb","@id":"https:\/\/a-eb.org\/#\/schema\/person\/325fa69af067b3a181046f67c79c67ff"},"headline":"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia","datePublished":"2025-06-10T08:36:43+00:00","dateModified":"2025-06-13T07:11:11+00:00","mainEntityOfPage":{"@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/"},"wordCount":89,"image":{"@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/Harley.png","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/","url":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/","name":"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","isPartOf":{"@id":"https:\/\/a-eb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#primaryimage"},"image":{"@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/Harley.png","datePublished":"2025-06-10T08:36:43+00:00","dateModified":"2025-06-13T07:11:11+00:00","author":{"@id":"https:\/\/a-eb.org\/#\/schema\/person\/325fa69af067b3a181046f67c79c67ff"},"breadcrumb":{"@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#primaryimage","url":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/Harley.png","contentUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/06\/Harley.png","width":1255,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/a-eb.org\/it\/vento-tra-i-capelli-gioia-nel-cuore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/a-eb.org\/it\/"},{"@type":"ListItem","position":2,"name":"Duri ma dal cuore grande Harley Heads MC S\u00fcdtirol \u2013 Canzone e amicizia"}]},{"@type":"WebSite","@id":"https:\/\/a-eb.org\/#website","url":"https:\/\/a-eb.org\/","name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","description":"AEB-Aktive Eltern von Menschen mit Behinderung VFG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-eb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/a-eb.org\/#\/schema\/person\/325fa69af067b3a181046f67c79c67ff","name":"a-eb","url":"https:\/\/a-eb.org\/it\/author\/a-eb\/"}]}},"_links":{"self":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/9690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/comments?post=9690"}],"version-history":[{"count":3,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/9690\/revisions"}],"predecessor-version":[{"id":9699,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/9690\/revisions\/9699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media\/9682"}],"wp:attachment":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media?parent=9690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/categories?post=9690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/tags?post=9690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}