{"id":9397,"date":"2025-06-10T10:38:58","date_gmt":"2025-06-10T08:38:58","guid":{"rendered":"https:\/\/a-eb.org\/?p=9397"},"modified":"2025-07-14T15:34:06","modified_gmt":"2025-07-14T13:34:06","slug":"5-promille-fuer-den-aeb","status":"publish","type":"post","link":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/","title":{"rendered":"5 per mille per l\u2018AEB"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\">Sostieni il nostro impegno con una firma nella dichiarazione dei redditi e indica il nostro codice fiscale per il <em>5 per mille<\/em> \u2013 un piccolo gesto per te, un grande aiuto per noi!<\/p>\n<h2 style=\"text-align: center;\"><strong>80024700215<\/strong><\/h2>\n<p style=\"text-align: center;\">Codice fiscale AEB<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/AEB_5PromilleKampagne_ok.mp4\">Video 5 per mille<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9415 aligncenter\" src=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-5-Promille-Video-1.png\" alt=\"\" width=\"282\" height=\"451\" srcset=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-5-Promille-Video-1.png 489w, https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-5-Promille-Video-1-188x300.png 188w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":9403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,6],"tags":[],"class_list":["post-9397","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 per mille per l\u2018AEB - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 per mille per l\u2018AEB - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/\" \/>\n<meta property=\"og:site_name\" content=\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-10T08:38:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T13:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-Website-5-Promille-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"a-eb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"a-eb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/\"},\"author\":{\"name\":\"a-eb\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/325fa69af067b3a181046f67c79c67ff\"},\"headline\":\"5 per mille per l\u2018AEB\",\"datePublished\":\"2025-06-10T08:38:58+00:00\",\"dateModified\":\"2025-07-14T13:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/\"},\"wordCount\":208,\"image\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Bild-Website-5-Promille-scaled.jpg\",\"articleSection\":[\"News\",\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/\",\"name\":\"5 per mille per l\u2018AEB - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Bild-Website-5-Promille-scaled.jpg\",\"datePublished\":\"2025-06-10T08:38:58+00:00\",\"dateModified\":\"2025-07-14T13:34:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/325fa69af067b3a181046f67c79c67ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Bild-Website-5-Promille-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Bild-Website-5-Promille-scaled.jpg\",\"width\":2560,\"height\":1363},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/5-promille-fuer-den-aeb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 per mille per l\u2018AEB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\",\"url\":\"https:\\\/\\\/a-eb.org\\\/\",\"name\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"description\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-eb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/325fa69af067b3a181046f67c79c67ff\",\"name\":\"a-eb\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/author\\\/a-eb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 per mille per l\u2018AEB - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/","og_locale":"it_IT","og_type":"article","og_title":"5 per mille per l\u2018AEB - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...","og_url":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/","og_site_name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","article_published_time":"2025-06-10T08:38:58+00:00","article_modified_time":"2025-07-14T13:34:06+00:00","og_image":[{"width":2560,"height":1363,"url":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-Website-5-Promille-scaled.jpg","type":"image\/jpeg"}],"author":"a-eb","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"a-eb","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#article","isPartOf":{"@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/"},"author":{"name":"a-eb","@id":"https:\/\/a-eb.org\/#\/schema\/person\/325fa69af067b3a181046f67c79c67ff"},"headline":"5 per mille per l\u2018AEB","datePublished":"2025-06-10T08:38:58+00:00","dateModified":"2025-07-14T13:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/"},"wordCount":208,"image":{"@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#primaryimage"},"thumbnailUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-Website-5-Promille-scaled.jpg","articleSection":["News","Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/","url":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/","name":"5 per mille per l\u2018AEB - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","isPartOf":{"@id":"https:\/\/a-eb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#primaryimage"},"image":{"@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#primaryimage"},"thumbnailUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-Website-5-Promille-scaled.jpg","datePublished":"2025-06-10T08:38:58+00:00","dateModified":"2025-07-14T13:34:06+00:00","author":{"@id":"https:\/\/a-eb.org\/#\/schema\/person\/325fa69af067b3a181046f67c79c67ff"},"breadcrumb":{"@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#primaryimage","url":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-Website-5-Promille-scaled.jpg","contentUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2025\/05\/Bild-Website-5-Promille-scaled.jpg","width":2560,"height":1363},{"@type":"BreadcrumbList","@id":"https:\/\/a-eb.org\/it\/5-promille-fuer-den-aeb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/a-eb.org\/it\/"},{"@type":"ListItem","position":2,"name":"5 per mille per l\u2018AEB"}]},{"@type":"WebSite","@id":"https:\/\/a-eb.org\/#website","url":"https:\/\/a-eb.org\/","name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","description":"AEB-Aktive Eltern von Menschen mit Behinderung VFG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-eb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/a-eb.org\/#\/schema\/person\/325fa69af067b3a181046f67c79c67ff","name":"a-eb","url":"https:\/\/a-eb.org\/it\/author\/a-eb\/"}]}},"_links":{"self":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/9397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/comments?post=9397"}],"version-history":[{"count":6,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/9397\/revisions"}],"predecessor-version":[{"id":9422,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/9397\/revisions\/9422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media\/9403"}],"wp:attachment":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media?parent=9397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/categories?post=9397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/tags?post=9397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}