{"id":4145,"date":"2022-02-24T09:24:17","date_gmt":"2022-02-24T08:24:17","guid":{"rendered":"https:\/\/a-eb.org\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/"},"modified":"2023-04-12T09:21:51","modified_gmt":"2023-04-12T07:21:51","slug":"cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani","status":"publish","type":"post","link":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/","title":{"rendered":"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2>Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani<\/h2>\n<p>Si \u00e8 spenta Gertrud Calenzani fondatrice ed a lungo presidente dell\u2019Associazione genitori di persone in situazione di handicap. Cordoglio dell\u2019assessora Deeg.<\/p>\n<p>Si \u00e8 spenta Gertrud G\u00e4nsbacher Calenzani, fondatrice nel 1979 dell\u2019Associazione genitori di persone in situazione di handicap (AEB), che ha presieduto sino al 2008. \u00c8 stata anche vicepresidente e componente del consiglio di amministrazione della cooperativa sociale &#8220;Novum&#8221;. L\u2019assessora provinciale alle politiche sociali, Waltraud Deeg, esprime il proprio cordoglio e ricorda il grande impegno della fondatrice a favore delle persone disabili e delle loro famiglie.<\/p>\n<p>\u201cGertrud Calenzani ha lottato instancabilmente \u2013 afferma l\u2019assessora Deeg &#8211; per dare voce alle esigenze ed ai diritti delle famiglie di persone disabili. \u00c8 grazie al suo impegno che nel 1983, con la legge provinciale nr. 20, \u00e8 stata data una nuova regolamentazione ai contributi destinati a questo settore&#8221;. Il suo contributo &#8220;\u00e8 stato determinante &#8211; aggiunge &#8211; anche per l\u2019istituzione dei soggiorni estivi per persone in situazione di handicap e la creazione degli alloggi protetti rivolti agli adulti. Ai suoi famigliari ed alla sua Associazione esprimo le mie sentite condoglianze\u201d. In considerazione del suo grande impegno nel 2016 \u00e8 stata conferita a Gertrud Calenzani la Medaglia al merito del Land Tirolo.[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-4145","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/\" \/>\n<meta property=\"og:site_name\" content=\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-24T08:24:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-12T07:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/02\/calenzanifotoklein.png\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"309\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"wp_AdminP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp_AdminP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/\"},\"author\":{\"name\":\"wp_AdminP\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/dffc4a03ef8f4f345668ca350e7361e5\"},\"headline\":\"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani\",\"datePublished\":\"2022-02-24T08:24:17+00:00\",\"dateModified\":\"2023-04-12T07:21:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/\"},\"wordCount\":361,\"image\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/calenzanifotoklein.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/\",\"name\":\"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/calenzanifotoklein.png\",\"datePublished\":\"2022-02-24T08:24:17+00:00\",\"dateModified\":\"2023-04-12T07:21:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/dffc4a03ef8f4f345668ca350e7361e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/calenzanifotoklein.png\",\"contentUrl\":\"https:\\\/\\\/a-eb.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/calenzanifotoklein.png\",\"width\":663,\"height\":309},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\",\"url\":\"https:\\\/\\\/a-eb.org\\\/\",\"name\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"description\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-eb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#\\\/schema\\\/person\\\/dffc4a03ef8f4f345668ca350e7361e5\",\"name\":\"wp_AdminP\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/author\\\/wp_adminp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/","og_locale":"it_IT","og_type":"article","og_title":"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...","og_url":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/","og_site_name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","article_published_time":"2022-02-24T08:24:17+00:00","article_modified_time":"2023-04-12T07:21:51+00:00","og_image":[{"width":663,"height":309,"url":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/02\/calenzanifotoklein.png","type":"image\/png"}],"author":"wp_AdminP","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"wp_AdminP","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#article","isPartOf":{"@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/"},"author":{"name":"wp_AdminP","@id":"https:\/\/a-eb.org\/#\/schema\/person\/dffc4a03ef8f4f345668ca350e7361e5"},"headline":"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani","datePublished":"2022-02-24T08:24:17+00:00","dateModified":"2023-04-12T07:21:51+00:00","mainEntityOfPage":{"@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/"},"wordCount":361,"image":{"@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#primaryimage"},"thumbnailUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/02\/calenzanifotoklein.png","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/","url":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/","name":"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","isPartOf":{"@id":"https:\/\/a-eb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#primaryimage"},"image":{"@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#primaryimage"},"thumbnailUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/02\/calenzanifotoklein.png","datePublished":"2022-02-24T08:24:17+00:00","dateModified":"2023-04-12T07:21:51+00:00","author":{"@id":"https:\/\/a-eb.org\/#\/schema\/person\/dffc4a03ef8f4f345668ca350e7361e5"},"breadcrumb":{"@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#primaryimage","url":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/02\/calenzanifotoklein.png","contentUrl":"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/02\/calenzanifotoklein.png","width":663,"height":309},{"@type":"BreadcrumbList","@id":"https:\/\/a-eb.org\/it\/cordoglio-dellassessora-deeg-per-la-scomparsa-di-gertrud-calenzani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/a-eb.org\/it\/"},{"@type":"ListItem","position":2,"name":"Cordoglio dell\u2019assessora Deeg per la scomparsa di Gertrud Calenzani"}]},{"@type":"WebSite","@id":"https:\/\/a-eb.org\/#website","url":"https:\/\/a-eb.org\/","name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","description":"AEB-Aktive Eltern von Menschen mit Behinderung VFG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-eb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/a-eb.org\/#\/schema\/person\/dffc4a03ef8f4f345668ca350e7361e5","name":"wp_AdminP","url":"https:\/\/a-eb.org\/it\/author\/wp_adminp\/"}]}},"_links":{"self":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/4145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/comments?post=4145"}],"version-history":[{"count":5,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/4145\/revisions"}],"predecessor-version":[{"id":4194,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/posts\/4145\/revisions\/4194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media\/1686"}],"wp:attachment":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media?parent=4145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/categories?post=4145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/tags?post=4145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}