{"id":2030,"date":"2021-09-16T17:07:40","date_gmt":"2021-09-16T15:07:40","guid":{"rendered":"http:\/\/a-eb.org.w01c4194.kasserver.com\/home\/"},"modified":"2025-12-19T09:44:56","modified_gmt":"2025-12-19T08:44:56","slug":"home","status":"publish","type":"page","link":"https:\/\/a-eb.org\/it\/","title":{"rendered":"Home"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;]<div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer \"><div  data-transition=\"fade\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"5000\" data-parallax=\"true\" data-parallax-disable-mobile=\"true\" data-caption-trans=\"none\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"false\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"450\" data-min-height=\"\" data-arrows=\"true\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" data-nectar-img-src=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/01\/aeb-1.jpg\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" data-nectar-img-src=\"https:\/\/a-eb.org\/wordpress\/wp-content\/uploads\/2022\/01\/aeb-2.jpg\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><a href=\"#\" aria-label=\"Previous\" class=\"slider-prev\"><i class=\"icon-salient-left-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a>\n\t\t\t\t\t\t<a href=\"#\" aria-label=\"Next\" class=\"slider-next\"><i class=\"icon-salient-right-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Un progetto per il futuro insieme all&#8217;AEB&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23f47e4b&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1697106583027{padding-bottom: 1% !important;}&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]L\u2019associazione &#8220;AEB \u2013 Genitori attivi per l&#8217;inclusione delle persone con disabilit\u00e0 APS&#8221; \u00e8 un\u2019associazione di persone direttamente interessate che rappresenta e promuove con determinazione e coraggio i bisogni delle persone con disabilit\u00e0 e delle loro famiglie, sia a livello sociale sia all\u2019interno delle strutture pubbliche.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][recent_posts style=&#8221;multiple_large_featured&#8221; large_featured_padding=&#8221;18%&#8221; mlf_navigation_location=&#8221;side&#8221; button_color=&#8221;Accent-Color&#8221; button_arrow_style=&#8221;default&#8221; load_in_animation=&#8221;none&#8221; large_featured_content_max_width=&#8221;default&#8221; bg_overlay=&#8221;diagonal_gradient&#8221; large_featured_heading_tag=&#8221;default&#8221; category=&#8221;all&#8221; multiple_large_featured_num=&#8221;3&#8243; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; auto_rotate=&#8221;4000&#8243; image_loading=&#8221;default&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; blog_remove_post_nectar_love=&#8221;true&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;iconsmind&#8221; url=&#8221;https:\/\/a-eb.org\/it\/news\/&#8221; text=&#8221;Vedi tutti i contributi&#8221; icon_iconsmind=&#8221;iconsmind-Triangle-ArrowRight&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f47e4b&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; bottom_padding=&#8221;80&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Diventa socio&#8221; font_container=&#8221;tag:h1|font_size:41px|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Dosis%3A200%2C300%2Cregular%2C500%2C600%2C700%2C800|font_style:600%20bold%20regular%3A600%3Anormal&#8221; css=&#8221;.vc_custom_1633421291003{padding-bottom: 2% !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1657008802200{margin-top: 15px !important;}&#8221;]\n<h2>Vantaggi di essere socio<\/h2>\n<ul>\n<li>Accesso a tutti gli eventi dell&#8217;associazione<\/li>\n<li>Consulenza gratuita su tutti i temi dell&#8217;associazione<\/li>\n<li>Invio periodico gratuito di lettere informative<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;right&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;see-through-3d&#8221; color_override=&#8221;#ffffff&#8221; url=&#8221;https:\/\/a-eb.org\/it\/contatti\/diventare-socio\/&#8221; text=&#8221;Al modulo di iscrizione&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2030","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-eb.org\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-eb.org\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T08:44:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\",\"name\":\"Home - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\"},\"datePublished\":\"2021-09-16T15:07:40+00:00\",\"dateModified\":\"2025-12-19T08:44:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-eb.org\\\/it\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\",\"url\":\"https:\\\/\\\/a-eb.org\\\/\",\"name\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"description\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-eb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-eb.org\/it\/","og_locale":"it_IT","og_type":"article","og_title":"Home - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;...","og_url":"https:\/\/a-eb.org\/it\/","og_site_name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","article_modified_time":"2025-12-19T08:44:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-eb.org\/it\/","url":"https:\/\/a-eb.org\/it\/","name":"Home - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","isPartOf":{"@id":"https:\/\/a-eb.org\/#website"},"datePublished":"2021-09-16T15:07:40+00:00","dateModified":"2025-12-19T08:44:56+00:00","breadcrumb":{"@id":"https:\/\/a-eb.org\/it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-eb.org\/it\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-eb.org\/it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/a-eb.org\/it\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/a-eb.org\/#website","url":"https:\/\/a-eb.org\/","name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","description":"AEB-Aktive Eltern von Menschen mit Behinderung VFG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-eb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages\/2030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/comments?post=2030"}],"version-history":[{"count":7,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages\/2030\/revisions"}],"predecessor-version":[{"id":10807,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages\/2030\/revisions\/10807"}],"wp:attachment":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media?parent=2030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}