{"id":10542,"date":"2025-12-04T15:42:27","date_gmt":"2025-12-04T14:42:27","guid":{"rendered":"https:\/\/a-eb.org\/?page_id=10542"},"modified":"2026-03-04T09:01:36","modified_gmt":"2026-03-04T08:01:36","slug":"mutpunkt-ubassa-atesina-oltradige-2026-2","status":"publish","type":"page","link":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/","title":{"rendered":"Mutpunkt &#8211; Bassa Atesina \/ Oltradige 2026"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h1><strong>Mutpunkt<\/strong><\/h1>\n<h4><strong>Tempo e spazio per giovani adulti con disabilit\u00e0 in Bassa Atesina \/ Oltradige<\/strong><\/h4>\n<p>A partire dal 2026, \u00abMutpunkt\u00bb accompagner\u00e0 i giovani adulti nella loro fase di transizione, rafforzando autostima, senso di valore e autonomia. I contenuti comprendono sviluppo personale, comunicazione, amicizia, temi quotidiani, creativit\u00e0, movimento ed esperienze nella natura. Gli incontri si svolgono una volta al mese di sabato, con in aggiunta due fine settimana opzionali in una casa autosufficiente.<\/p>\n<p><strong>Team<\/strong><\/p>\n<p>Alexa Bachmann (Leitung),\u00a0Silas Brunato (Co-Leitung),\u00a0Greta Micheli,\u00a0Ruben Pratissoli,\u00a0Josef Trebo[\/vc_column_text][image_with_animation image_url=&#8221;10545&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Fotos \u00a9 Markus Zimmerhofer &#8211; Somnias[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10542","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mutpunkt - Bassa Atesina \/ Oltradige 2026 - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mutpunkt - Bassa Atesina \/ Oltradige 2026 - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/\" \/>\n<meta property=\"og:site_name\" content=\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T08:01:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/mutpunkt-ubassa-atesina-oltradige-2026-2\\\/\",\"url\":\"https:\\\/\\\/a-eb.org\\\/it\\\/mutpunkt-ubassa-atesina-oltradige-2026-2\\\/\",\"name\":\"Mutpunkt - Bassa Atesina \\\/ Oltradige 2026 - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\"},\"datePublished\":\"2025-12-04T14:42:27+00:00\",\"dateModified\":\"2026-03-04T08:01:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/mutpunkt-ubassa-atesina-oltradige-2026-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-eb.org\\\/it\\\/mutpunkt-ubassa-atesina-oltradige-2026-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/it\\\/mutpunkt-ubassa-atesina-oltradige-2026-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/a-eb.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mutpunkt &#8211; Bassa Atesina \\\/ Oltradige 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-eb.org\\\/#website\",\"url\":\"https:\\\/\\\/a-eb.org\\\/\",\"name\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol\",\"description\":\"AEB-Aktive Eltern von Menschen mit Behinderung VFG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-eb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mutpunkt - Bassa Atesina \/ Oltradige 2026 - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/","og_locale":"it_IT","og_type":"article","og_title":"Mutpunkt - Bassa Atesina \/ Oltradige 2026 - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column...","og_url":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/","og_site_name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","article_modified_time":"2026-03-04T08:01:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/","url":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/","name":"Mutpunkt - Bassa Atesina \/ Oltradige 2026 - AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","isPartOf":{"@id":"https:\/\/a-eb.org\/#website"},"datePublished":"2025-12-04T14:42:27+00:00","dateModified":"2026-03-04T08:01:36+00:00","breadcrumb":{"@id":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-eb.org\/it\/mutpunkt-ubassa-atesina-oltradige-2026-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/a-eb.org\/it\/"},{"@type":"ListItem","position":2,"name":"Mutpunkt &#8211; Bassa Atesina \/ Oltradige 2026"}]},{"@type":"WebSite","@id":"https:\/\/a-eb.org\/#website","url":"https:\/\/a-eb.org\/","name":"AEB-Aktive Eltern von Menschen mit Behinderung VFG | Bozen | S\u00fcdtirol","description":"AEB-Aktive Eltern von Menschen mit Behinderung VFG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-eb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages\/10542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/comments?post=10542"}],"version-history":[{"count":8,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages\/10542\/revisions"}],"predecessor-version":[{"id":11188,"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/pages\/10542\/revisions\/11188"}],"wp:attachment":[{"href":"https:\/\/a-eb.org\/it\/wp-json\/wp\/v2\/media?parent=10542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}